{"id":921,"date":"2021-01-08T10:53:32","date_gmt":"2021-01-08T10:53:32","guid":{"rendered":"https:\/\/www.dksb-nordenham.de\/?p=921"},"modified":"2023-06-06T13:15:31","modified_gmt":"2023-06-06T13:15:31","slug":"kinderschutzbund-schnuert-lernpakete","status":"publish","type":"post","link":"https:\/\/www.dksb-nordenham.de\/index.php\/2021\/01\/08\/kinderschutzbund-schnuert-lernpakete\/","title":{"rendered":"Kinderschutzbund schn\u00fcrt Lernpakete"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die coronabedingten &#8222;Zwangsferien&#8220; m\u00f6gen zun\u00e4chst als geschenkte freie Zeit von den Sch\u00fcler*innen empfunden worden sein. Mittlerweile aber machen sich Eltern als auch Kinder Sorgen \u00fcber den Schulausfall und seine Folgen. Zwar werden von vielen Schulen Hausaufgaben via Internet gestellt. Viele Kinder ben\u00f6tigen jedoch bei der Anfertigung dieser Hausaufgaben Unterst\u00fctzung, die sie im Rahmen der Lernf\u00f6rderung durch den Kinderschutzbund, Ortsverband Nordenham, regelm\u00e4\u00dfig in Anspruch nehmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Programm &#8222;Anders lernen&#8220; (siehe Rubrik Bildung und Unterst\u00fctzung\/Lernf\u00f6rderung) soll helfen, L\u00fccken im Lernstoff zu schlie\u00dfen bzw. gar nicht erst entstehen zu lassen. Mitarbeiter*innen des Kinderschutzbundes wollen jetzt Lernpakete, individuell auf die einzelnen Sch\u00fcler*innen zugeschnitten, schn\u00fcren.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Die coronabedingten &#8222;Zwangsferien&#8220; m\u00f6gen zun\u00e4chst als geschenkte freie Zeit von den Sch\u00fcler*innen empfunden worden sein. Mittlerweile aber machen sich Eltern als auch Kinder Sorgen \u00fcber den Schulausfall und seine Folgen. Zwar werden von vielen Schulen Hausaufgaben via Internet gestellt. Viele Kinder ben\u00f6tigen jedoch bei der Anfertigung dieser Hausaufgaben Unterst\u00fctzung, die sie im Rahmen der Lernf\u00f6rderung [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-921","post","type-post","status-publish","format-standard","hentry","category-bildung-und-unterstuetzung"],"_links":{"self":[{"href":"https:\/\/www.dksb-nordenham.de\/index.php\/wp-json\/wp\/v2\/posts\/921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dksb-nordenham.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dksb-nordenham.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dksb-nordenham.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dksb-nordenham.de\/index.php\/wp-json\/wp\/v2\/comments?post=921"}],"version-history":[{"count":3,"href":"https:\/\/www.dksb-nordenham.de\/index.php\/wp-json\/wp\/v2\/posts\/921\/revisions"}],"predecessor-version":[{"id":1293,"href":"https:\/\/www.dksb-nordenham.de\/index.php\/wp-json\/wp\/v2\/posts\/921\/revisions\/1293"}],"wp:attachment":[{"href":"https:\/\/www.dksb-nordenham.de\/index.php\/wp-json\/wp\/v2\/media?parent=921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dksb-nordenham.de\/index.php\/wp-json\/wp\/v2\/categories?post=921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dksb-nordenham.de\/index.php\/wp-json\/wp\/v2\/tags?post=921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}